{"id":30149,"date":"2026-02-13T15:40:38","date_gmt":"2026-02-13T15:40:38","guid":{"rendered":"https:\/\/www.bpa-solutions.net\/?page_id=30149"},"modified":"2026-02-17T13:44:37","modified_gmt":"2026-02-17T13:44:37","slug":"compliance-with-iso13485","status":"publish","type":"page","link":"https:\/\/www.bpa-solutions.net\/fr\/compliance-with-bpa\/compliance-with-iso13485\/","title":{"rendered":"Compliance with ISO13485"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;Title&#8221; module_id=&#8221;partner-program&#8221; module_class=&#8221;software-banner&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; vertical_offset_tablet=&#8221;0&#8243; horizontal_offset_tablet=&#8221;0&#8243; width=&#8221;90%&#8221; max_width=&#8221;1600px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;150px|0px|75px|0px|false|false&#8221; custom_padding_tablet=&#8221;150px|0px|25px|0px|false|false&#8221; custom_padding_phone=&#8221;||0px||false|false&#8221; hover_transition_duration=&#8221;0ms&#8221; background_image_tablet=&#8221;https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2023\/07\/Document-Control-Software-tablet.png&#8221; background_enable_image_tablet=&#8221;on&#8221; background_enable_image_phone=&#8221;off&#8221; custom_css_free_form=&#8221;selector p{color:#343434 !important}&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_css_before__hover_enabled=&#8221;on|desktop&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; make_equal=&#8221;on&#8221; module_id=&#8221;hero-row-text-img&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;breadcrumbs&#8221; module_class=&#8221;breadcrumbs&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; vertical_offset_tablet=&#8221;0&#8243; horizontal_offset_tablet=&#8221;0&#8243; z_index_tablet=&#8221;0&#8243; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; global_module=&#8221;19802&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;]<span><span><a href=\"https:\/\/www.bpa-solutions.net\/\">Home<\/a><\/span><\/span><!-- [et_pb_line_break_holder] -->[\/et_pb_code][et_pb_heading title=&#8221;ISO\/IEC 13485 made practical&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;50px||50px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>ISO 13485:2016 is the international benchmark for quality management systems in the medical device industry, defining strict requirements to ensure product safety, regulatory compliance, and full traceability across the product life cycle. As global regulations increasingly align with ISO 13485, organizations must implement structured, risk based, and audit ready processes that go beyond documentation and enable effective operational compliance.<\/p>\n<p>Our ISO 13485 standard to feature mapping guide shows how BPAMedical365, directly supports each clause through integrated document control, CAPA, supplier management, traceability, and automated workflows.<\/p>\n<p>Download the guidebook to explore the detailed clause by clause mapping and learn how BPA enables efficient, secure, and scalable ISO 13485 compliance.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#Guidebook-form&#8221; button_text=&#8221;Download guidebook&#8221; module_class=&#8221;primary-cta&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_bg_color=&#8221;#9dc73b&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;4px&#8221; button_icon=&#8221;&#xf061;||fa||900&#8243; button_on_hover=&#8221;off&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;10px||40px||false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;10px|45px|10px|25px|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-19-093025.png&#8221; alt=&#8221;ISO\/IEC 27001 made practical&#8221; title_text=&#8221;ISO\/IEC 27001 made practical&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Advanced Features Grid&#8221; module_id=&#8221;features-block&#8221; module_class=&#8221;section-features-block&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;1600px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;55px||10px||false|false&#8221; custom_margin_tablet=&#8221;25px||25px||false|false&#8221; custom_margin_phone=&#8221;||0px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; custom_css_free_form=&#8221;selector .list-item{|| display:flex !important;|| flex-direction:column;|| column-gap: 10px !important;|| pointer-events:none !important;||}||selector .list-item:hover{|| background:transparent !important;|| height:20px !important;||}||||#features-block li{|| font-size:14px;|| line-height: 2||}||#features-block ul {|| list-style-image: url(&#8216;https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2024\/04\/checkbox.svg&#8217;);|| list-style-position: outside;|| padding-left:25px;||}&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Grid&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#40690d&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;293deg&#8221; background_color_gradient_stops=&#8221;#93bc22 0%|#425b10 100%&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; custom_css_main_element=&#8221;display:flex;||flex-direction:column;||justify-content: flex-start;||align-items: flex-start;||column-gap: 25px;&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Clause 4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;GENERAL REQUIREMENTS&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h5&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h6&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text module_class=&#8221;form-text&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.3em&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_6_text_color=&#8221;#FFFFFF&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\">Establish and maintain a compliant QMS, including a controlled Quality Manual defining scope and processes. Define and assign roles and responsibilities to ensure accountability and traceability. Maintain Medical Device Files with complete design, specification, and manufacturing documentation. Control documents with approval workflows, version control, and revision tracking. Manage document and record lifecycle, ensuring secure storage, traceability and proper disposal.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; admin_label=&#8221;Item&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#343434&#8243; text_font_size=&#8221;14px&#8221; text_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong><span style=\"color: #343434;\">How BPA eQMS helps<\/span><\/strong><\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li>\n<p>Import master data in the eQMS prebuilt modules through the grid mode: organization chart, plants and departments with responsible persons; processes, owners, approvers, visual process map; collaborators, jobs and job description; ISO 13485 clauses and chapters; context<\/p>\n<\/li>\n<li>\n<p>Create\/import documents in Compliance Documents, update\/create document\/form templates and publish them.<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; admin_label=&#8221;Item&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#343434&#8243; text_font_size=&#8221;14px&#8221; text_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong><span style=\"color: #343434;\">Concerned BPA modules<\/span><\/strong><\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li>\n<p>Process management<\/p>\n<\/li>\n<li>\n<p>Document control<\/p>\n<\/li>\n<li>\n<p>Technical files<\/p>\n<\/li>\n<li>\n<p>Forms management<\/p>\n<\/li>\n<li>\n<p>Q-Pilot<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Advanced Features Grid&#8221; module_id=&#8221;features-block&#8221; module_class=&#8221;section-features-block&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;1600px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; custom_margin_tablet=&#8221;25px||25px||false|false&#8221; custom_margin_phone=&#8221;||0px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; custom_css_free_form=&#8221;selector .list-item{|| display:flex !important;|| flex-direction:column;|| column-gap: 10px !important;|| pointer-events:none !important;||}||selector .list-item:hover{|| background:transparent !important;|| height:20px !important;||}||||#features-block li{|| font-size:14px;|| line-height: 2||}||#features-block ul {|| list-style-image: url(&#8216;https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2024\/04\/checkbox.svg&#8217;);|| list-style-position: outside;|| padding-left:25px;||}&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Grid&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;293deg&#8221; background_color_gradient_stops=&#8221;#f9b900 0%|#aa7519 100%&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; custom_css_main_element=&#8221;display:flex;||flex-direction:column;||justify-content: flex-start;||align-items: flex-start;||column-gap: 25px;&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Clause 5&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;MANAGEMENT RESPONSIBILITY&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h5&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h6&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text module_class=&#8221;form-text&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.3em&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_6_text_color=&#8221;#FFFFFF&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Ensure top management commitment to QMS effectiveness and regulatory compliance. Establish a quality policy and measurable quality objectives aligned with organizational goals. Define roles, responsibilities, and ensure effective internal communication. Conduct regular management reviews to monitor performance and drive improvement.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; admin_label=&#8221;Item&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#343434&#8243; text_font_size=&#8221;14px&#8221; text_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong><span style=\"color: #343434;\">How BPA eQMS helps<\/span><\/strong><\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li>\n<p>Publish organization structure, roles, and responsibilities within the eQMS.<\/p>\n<\/li>\n<li>\n<p>Publish quality policy and manage quality objectives with automated KPI tracking.<\/p>\n<\/li>\n<li>\n<p>Collect and centralize customer feedback using integrated MS Forms surveys.<\/p>\n<\/li>\n<li>\n<p>Collaborate through built in discussion flows and manage actions with integrated task management.<\/p>\n<\/li>\n<li>\n<p>Plan, execute, and document management reviews with automated notifications and Power BI performance reporting.<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; admin_label=&#8221;Item&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#343434&#8243; text_font_size=&#8221;14px&#8221; text_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong><span style=\"color: #343434;\">Concerned BPA modules<\/span><\/strong><\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li>Document Control<\/li>\n<li>Process management<\/li>\n<li>Stakeholder management<\/li>\n<li>Indicator management<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Advanced Features Grid&#8221; module_id=&#8221;features-block&#8221; module_class=&#8221;section-features-block&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;1600px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; custom_margin_tablet=&#8221;25px||25px||false|false&#8221; custom_margin_phone=&#8221;||0px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; custom_css_free_form=&#8221;selector .list-item{|| display:flex !important;|| flex-direction:column;|| column-gap: 10px !important;|| pointer-events:none !important;||}||selector .list-item:hover{|| background:transparent !important;|| height:20px !important;||}||||#features-block li{|| font-size:14px;|| line-height: 2||}||#features-block ul {|| list-style-image: url(&#8216;https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2024\/04\/checkbox.svg&#8217;);|| list-style-position: outside;|| padding-left:25px;||}&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Grid&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;293deg&#8221; background_color_gradient_stops=&#8221;#e24617 0%|#6d0b04 99%&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; custom_css_main_element=&#8221;display:flex;||flex-direction:column;||justify-content: flex-start;||align-items: flex-start;||column-gap: 25px;&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Clause 6&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;RESOURCE MANAGEMENT&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h5&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h6&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text module_class=&#8221;form-text&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.3em&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_6_text_color=&#8221;#FFFFFF&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Provide and maintain adequate resources to ensure QMS effectiveness and product conformity. Ensure personnel are competent through appropriate training and maintain training records. Maintain required infrastructure and a controlled work environment to safeguard product quality and prevent contamination.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; admin_label=&#8221;Item&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#343434&#8243; text_font_size=&#8221;14px&#8221; text_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong><span style=\"color: #343434;\">How BPA eQMS helps<\/span><\/strong><\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li>\n<p>Manage personnel, roles, and competencies with automated competency assessment.<\/p>\n<\/li>\n<li>\n<p>Track equipment and assets, including verification schedules and corrective actions.<\/p>\n<\/li>\n<li>\n<p>Create, approve, train, and publish operational procedures using automated workflows.<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; admin_label=&#8221;Item&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#343434&#8243; text_font_size=&#8221;14px&#8221; text_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong><span style=\"color: #343434;\">Concerned BPA modules<\/span><\/strong><\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li>Document control<\/li>\n<li>Training management<\/li>\n<li>Equipment\/asset management<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Advanced Features Grid&#8221; module_id=&#8221;features-block&#8221; module_class=&#8221;section-features-block&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;1600px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; custom_margin_tablet=&#8221;25px||25px||false|false&#8221; custom_margin_phone=&#8221;||0px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; custom_css_free_form=&#8221;selector .list-item{|| display:flex !important;|| flex-direction:column;|| column-gap: 10px !important;|| pointer-events:none !important;||}||selector .list-item:hover{|| background:transparent !important;|| height:20px !important;||}||||#features-block li{|| font-size:14px;|| line-height: 2||}||#features-block ul {|| list-style-image: url(&#8216;https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2024\/04\/checkbox.svg&#8217;);|| list-style-position: outside;|| padding-left:25px;||}&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Grid&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;293deg&#8221; background_color_gradient_stops=&#8221;#3e9fd9 0%|#286d9b 100%&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; custom_css_main_element=&#8221;display:flex;||flex-direction:column;||justify-content: flex-start;||align-items: flex-start;||column-gap: 25px;&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Clause 7&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;PRODUCT REALIZATION&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h5&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h6&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text module_class=&#8221;form-text&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.3em&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_6_text_color=&#8221;#FFFFFF&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Plan and control product realization processes, including risk management and quality objectives. Define, review, and communicate customer and regulatory requirements. Control design and development with documented planning, verification, validation, and change management. Evaluate and monitor suppliers, and verify purchased products. Control production processes, including validation of special processes, identification, traceability, and product preservation. Ensure equipment is calibrated and maintained to guarantee accurate measurements<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; admin_label=&#8221;Item&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#343434&#8243; text_font_size=&#8221;14px&#8221; text_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong><span style=\"color: #343434;\">How BPA eQMS helps<\/span><\/strong><\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li>\n<p>Manage risks and opportunities using prebuilt workflows based on FMEA, PHA, and ISO 14971, including initial, residual, and periodic assessments.<\/p>\n<\/li>\n<li>\n<p>Import or create compliance procedures for customer, regulatory, and product requirements, collect approvals and training, and publish them.<\/p>\n<\/li>\n<li>\n<p>Collect and centralize customer feedback and complaints via MS Forms with automated data capture in the eQMS.<\/p>\n<\/li>\n<li>\n<p>Control product and service design with document management, versioning, approvals, and creation of design or device history files.<\/p>\n<\/li>\n<li>\n<p>Manage suppliers through evaluation, approval, audits, and nonconformity tracking with prebuilt supplier modules.<\/p>\n<\/li>\n<li>\n<p>Track training, document approvals, and asset verification using preconfigured automation for efficient compliance management.<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; admin_label=&#8221;Item&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#343434&#8243; text_font_size=&#8221;14px&#8221; text_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong><span style=\"color: #343434;\">Concerned BPA modules<\/span><\/strong><\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li>\n<p>Risk management<\/p>\n<\/li>\n<li>\n<p>Health and safety<\/p>\n<\/li>\n<li>\n<p>Document control<\/p>\n<\/li>\n<li>\n<p>Technical Files<\/p>\n<\/li>\n<li>\n<p>Change management<\/p>\n<\/li>\n<li>\n<p>Nonconformities management<\/p>\n<\/li>\n<li>\n<p>Audit management<\/p>\n<\/li>\n<li>\n<p>CAPA<\/p>\n<\/li>\n<li>\n<p>Equipment Management<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Advanced Features Grid&#8221; module_id=&#8221;features-block&#8221; module_class=&#8221;section-features-block&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;1600px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; custom_margin_tablet=&#8221;25px||25px||false|false&#8221; custom_margin_phone=&#8221;||0px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; custom_css_free_form=&#8221;selector .list-item{|| display:flex !important;|| flex-direction:column;|| column-gap: 10px !important;|| pointer-events:none !important;||}||selector .list-item:hover{|| background:transparent !important;|| height:20px !important;||}||||#features-block li{|| font-size:14px;|| line-height: 2||}||#features-block ul {|| list-style-image: url(&#8216;https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2024\/04\/checkbox.svg&#8217;);|| list-style-position: outside;|| padding-left:25px;||}&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Grid&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#40690d&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;293deg&#8221; background_color_gradient_stops=&#8221;#93bc22 0%|#425b10 100%&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; custom_css_main_element=&#8221;display:flex;||flex-direction:column;||justify-content: flex-start;||align-items: flex-start;||column-gap: 25px;&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Clause 8&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;MEASUREMENT, ANALYSIS AND IMPROVEMENT&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h5&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h6&#8243; title_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text module_class=&#8221;form-text&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.3em&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_6_text_color=&#8221;#FFFFFF&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Establish processes to monitor, measure, analyze, and improve product quality and QMS performance. Collect and assess feedback, maintain procedures for complaints, production monitoring, audits, and regulatory reporting. Identify and control nonconforming products and apply CAPA. Review data such as feedback, nonconformities, audits, and supplier performance to evaluate QMS effectiveness. Drive continuous improvement through quality objectives, audits, post\u2011market data, performance analysis, CAPA, and management reviews.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; admin_label=&#8221;Item&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#343434&#8243; text_font_size=&#8221;14px&#8221; text_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong><span style=\"color: #343434;\">How BPA eQMS helps<\/span><\/strong><\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li>\n<p>BPA provides preconfigured modules for document creation, approval, training, and publication.<\/p>\n<\/li>\n<li>\n<p>It also includes modules for managing clients, customer feedback, complaints, internal audits, nonconformities, corrective actions, risks, and objectives.<\/p>\n<\/li>\n<li>\n<p>BPA offers preconfigured Power BI reports across key modules, such as actions, audits, nonconformities, document training, and risks, which can be combined into a comprehensive eQMS performance report for management reviews.<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; admin_label=&#8221;Item&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#d9d9d9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#343434&#8243; text_font_size=&#8221;14px&#8221; text_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><strong><span style=\"color: #343434;\">Concerned BPA modules<\/span><\/strong><\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li>Document control<\/li>\n<li>Audit management<\/li>\n<li>Nonconformities management<\/li>\n<li>CAPA\u00a0<\/li>\n<li>Risk management<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Popup Form: Brochure Download&#8221; module_id=&#8221;brochure-download&#8221; module_class=&#8221;popup-form trial-request-sec free-trial-sec brochure-sec contact-form-section&#8221; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(0,0,0,0.5)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; max_width=&#8221;758px&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;440px&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; custom_css_free_form=&#8221;selector{|| padding-left:0 !important;|| padding-right:0 !important;||}&#8221; border_radii=&#8221;on|3px|3px|3px|3px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(0,0,0,0.24)&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;23deg&#8221; background_color_gradient_stops=&#8221;#6b8a44 0%|#bbd983 100%&#8221; background_image=&#8221;https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2024\/04\/Background1.png&#8221; background_blend=&#8221;multiply&#8221; custom_padding=&#8221;35px|35px|35px|35px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Access additional resources for this solution&#8221; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h2&#8243; title_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]Fill out the form and gain access to our variety of specific resources: Technical videos, tips for using each solution and much more.[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;35px|35px|35px|35px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_icon font_icon=&#8221;&#x4d;||divi||400&#8243; icon_color=&#8221;#000000&#8243; icon_width=&#8221;22px&#8221; align=&#8221;right&#8221; admin_label=&#8221;Icon&#8221; module_id=&#8221;close-brochure-form&#8221; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_icon][et_pb_code module_class=&#8221;free-trial-form&#8221; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f24910-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"24910\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/30149#wpcf7-f24910-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"24910\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f24910-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"free-trial-form\">\n\t<div class=\"company-continer\">\n\t\t<div class=\"cont\">\n\t\t\t<p><label> Business Email <span class=\"req\">*<\/span><\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Work Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"company-continer\">\n\t\t<div class=\"cont\">\n\t\t\t<p><label> First Name <span class=\"req\">*<\/span><\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"First Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"cont\">\n\t\t\t<p><label> Last Name <span class=\"req\">*<\/span><\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"lastname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Last Name\" value=\"\" type=\"text\" name=\"lastname\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"company-continer\">\n\t\t<div class=\"cont\">\n\t\t\t<p><label> Company <span class=\"req\">*<\/span><\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company Name\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"cont company-select search-drop-cont\">\n\t\t\t<p><label>Country <span class=\"req\">*<\/span><\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"select-country\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required country-dropdown\" id=\"search-dropdown-broch\" aria-required=\"true\" aria-invalid=\"false\" name=\"select-country\"><option value=\"\">Country<\/option><option value=\"US\">United States<\/option><option value=\"AF\">Afghanistan<\/option><option value=\"AX\">\u00c5land Islands<\/option><option value=\"AL\">Albania<\/option><option value=\"DZ\">Algeria<\/option><option value=\"AS\">American Samoa<\/option><option value=\"AD\">Andorra<\/option><option value=\"AO\">Angola<\/option><option value=\"AI\">Anguilla<\/option><option value=\"AG\">Antigua and Barbuda<\/option><option value=\"AR\">Argentina<\/option><option value=\"AM\">Armenia<\/option><option value=\"AW\">Aruba<\/option><option value=\"AC\">Ascension<\/option><option value=\"AU\">Australia<\/option><option value=\"AT\">Austria<\/option><option value=\"AZ\">Azerbaijan<\/option><option value=\"BS\">Bahamas<\/option><option value=\"BH\">Bahrain<\/option><option value=\"BB\">Barbados<\/option><option value=\"BY\">Belarus<\/option><option value=\"BE\">Belgium<\/option><option value=\"BZ\">Belize<\/option><option value=\"BJ\">Benin<\/option><option value=\"BM\">Bermuda<\/option><option value=\"BT\">Bhutan<\/option><option value=\"BO\">Bolivia, Plurinational State of<\/option><option value=\"BQ\">Bonaire, Sint Eustatius and Saba<\/option><option value=\"BA\">Bosnia and Herzegovina<\/option><option value=\"BW\">Botswana<\/option><option value=\"BR\">Brazil<\/option><option value=\"IO\">British Indian Ocean Territory<\/option><option value=\"BN\">Brunei Darussalam<\/option><option value=\"BG\">Bulgaria<\/option><option value=\"BF\">Burkina Faso<\/option><option value=\"BI\">Burundi<\/option><option value=\"KH\">Cambodia<\/option><option value=\"CM\">Cameroon<\/option><option value=\"CA\">Canada<\/option><option value=\"IC\">Canary Islands<\/option><option value=\"CV\">Cape Verde<\/option><option value=\"KY\">Cayman Islands<\/option><option value=\"CF\">Central African Republic<\/option><option value=\"TD\">Chad<\/option><option value=\"CL\">Chile<\/option><option value=\"CN\">China<\/option><option value=\"CX\">Christmas Island<\/option><option value=\"CC\">Cocos (Keeling) Islands<\/option><option value=\"CO\">Colombia<\/option><option value=\"KM\">Comoros<\/option><option value=\"CG\">Congo<\/option><option value=\"CD\">Congo, the Democratic Republic of the<\/option><option value=\"CK\">Cook Islands<\/option><option value=\"CR\">Costa Rica<\/option><option value=\"CI\">C\u00f4te d&#039;Ivoire<\/option><option value=\"HR\">Croatia<\/option><option value=\"CU\">Cuba<\/option><option value=\"CW\">Cura\u00e7ao<\/option><option value=\"CY\">Cyprus<\/option><option value=\"CZ\">Czech Republic<\/option><option value=\"DK\">Denmark<\/option><option value=\"DG\">Diego Garcia<\/option><option value=\"DJ\">Djibouti<\/option><option value=\"DM\">Dominica<\/option><option value=\"DO\">Dominican Republic<\/option><option value=\"EC\">Ecuador<\/option><option value=\"EG\">Egypt<\/option><option value=\"SV\">El Salvador<\/option><option value=\"GQ\">Equatorial Guinea<\/option><option value=\"ER\">Eritrea<\/option><option value=\"EE\">Estonia<\/option><option value=\"ET\">Ethiopia<\/option><option value=\"FK\">Falkland Islands (Malvinas)<\/option><option value=\"FO\">Faroe Islands<\/option><option value=\"FJ\">Fiji<\/option><option value=\"FI\">Finland<\/option><option value=\"FR\">France<\/option><option value=\"GF\">French Guiana<\/option><option value=\"PF\">French Polynesia<\/option><option value=\"GA\">Gabon<\/option><option value=\"GM\">Gambia<\/option><option value=\"GE\">Georgia<\/option><option value=\"DE\">Germany<\/option><option value=\"GH\">Ghana<\/option><option value=\"GI\">Gibraltar<\/option><option value=\"GR\">Greece<\/option><option value=\"GL\">Greenland<\/option><option value=\"GD\">Grenada<\/option><option value=\"GP\">Guadeloupe<\/option><option value=\"GU\">Guam<\/option><option value=\"GT\">Guatemala<\/option><option value=\"GG\">Guernsey<\/option><option value=\"GN\">Guinea<\/option><option value=\"GW\">Guinea-Bissau<\/option><option value=\"GY\">Guyana<\/option><option value=\"HT\">Haiti<\/option><option value=\"HM\">Heard Island and McDonald Islands<\/option><option value=\"VA\">Holy See (Vatican City State)<\/option><option value=\"HN\">Honduras<\/option><option value=\"HK\">Hong Kong<\/option><option value=\"HU\">Hungary<\/option><option value=\"IS\">Iceland<\/option><option value=\"ID\">Indonesia<\/option><option value=\"IR\">Iran, Islamic Republic of<\/option><option value=\"IQ\">Iraq<\/option><option value=\"IE\">Ireland<\/option><option value=\"IM\">Isle of Man<\/option><option value=\"IL\">Israel<\/option><option value=\"IT\">Italy<\/option><option value=\"JM\">Jamaica<\/option><option value=\"JP\">Japan<\/option><option value=\"JE\">Jersey<\/option><option value=\"JO\">Jordan<\/option><option value=\"KZ\">Kazakhstan<\/option><option value=\"KE\">Kenya<\/option><option value=\"KI\">Kiribati<\/option><option value=\"KP\">Korea, Democratic People&#039;s Republic of<\/option><option value=\"KR\">Korea, Republic of<\/option><option value=\"KW\">Kuwait<\/option><option value=\"KG\">Kyrgyzstan<\/option><option value=\"LA\">Lao People&#039;s Democratic Republic<\/option><option value=\"LV\">Latvia<\/option><option value=\"LB\">Lebanon<\/option><option value=\"LS\">Lesotho<\/option><option value=\"LR\">Liberia<\/option><option value=\"LY\">Libya<\/option><option value=\"LI\">Liechtenstein<\/option><option value=\"LT\">Lithuania<\/option><option value=\"LU\">Luxembourg<\/option><option value=\"MO\">Macao<\/option><option value=\"MK\">Macedonia, the former Yugoslav Republic of<\/option><option value=\"MG\">Madagascar<\/option><option value=\"MW\">Malawi<\/option><option value=\"MY\">Malaysia<\/option><option value=\"MV\">Maldives<\/option><option value=\"ML\">Mali<\/option><option value=\"MT\">Malta<\/option><option value=\"MH\">Marshall Islands<\/option><option value=\"MQ\">Martinique<\/option><option value=\"MR\">Mauritania<\/option><option value=\"MU\">Mauritius<\/option><option value=\"YT\">Mayotte<\/option><option value=\"MX\">Mexico<\/option><option value=\"FM\">Micronesia, Federated States of<\/option><option value=\"MD\">Moldova, Republic of<\/option><option value=\"MC\">Monaco<\/option><option value=\"MN\">Mongolia<\/option><option value=\"ME\">Montenegro<\/option><option value=\"MS\">Montserrat<\/option><option value=\"MA\">Morocco<\/option><option value=\"MZ\">Mozambique<\/option><option value=\"MM\">Myanmar<\/option><option value=\"NA\">Namibia<\/option><option value=\"NR\">Nauru<\/option><option value=\"NP\">Nepal<\/option><option value=\"NL\">Netherlands<\/option><option value=\"AN\">Netherlands Antilles<\/option><option value=\"NC\">New Caledonia<\/option><option value=\"NZ\">New Zealand<\/option><option value=\"NI\">Nicaragua<\/option><option value=\"NE\">Niger<\/option><option value=\"NG\">Nigeria<\/option><option value=\"NU\">Niue<\/option><option value=\"NF\">Norfolk Island<\/option><option value=\"MP\">Northern Mariana Islands<\/option><option value=\"NO\">Norway<\/option><option value=\"OM\">Oman<\/option><option value=\"PW\">Palau<\/option><option value=\"PS\">Palestinian Territory, Occupied<\/option><option value=\"PA\">Panama<\/option><option value=\"PG\">Papua New Guinea<\/option><option value=\"PY\">Paraguay<\/option><option value=\"PE\">Peru<\/option><option value=\"PH\">Philippines<\/option><option value=\"PN\">Pitcairn<\/option><option value=\"PL\">Poland<\/option><option value=\"PT\">Portugal<\/option><option value=\"PR\">Puerto Rico<\/option><option value=\"QA\">Qatar<\/option><option value=\"RE\">R\u00e9union<\/option><option value=\"RO\">Romania<\/option><option value=\"RU\">Russian Federation<\/option><option value=\"RW\">Rwanda<\/option><option value=\"BL\">Saint Barth\u00e9lemy<\/option><option value=\"SH\">Saint Helena, Ascension and Tristan da Cunha<\/option><option value=\"KN\">Saint Kitts and Nevis<\/option><option value=\"LC\">Saint Lucia<\/option><option value=\"MF\">Saint Martin (French part)<\/option><option value=\"PM\">Saint Pierre and Miquelon<\/option><option value=\"VC\">Saint Vincent and the Grenadines<\/option><option value=\"WS\">Samoa<\/option><option value=\"SM\">San Marino<\/option><option value=\"ST\">Sao Tome and Principe<\/option><option value=\"SA\">Saudi Arabia<\/option><option value=\"NT\">Saudi\u2013Iraqi neutral zone<\/option><option value=\"SN\">Senegal<\/option><option value=\"RS\">Serbia<\/option><option value=\"SC\">Seychelles<\/option><option value=\"SL\">Sierra Leone<\/option><option value=\"SG\">Singapore<\/option><option value=\"SX\">Sint Maarten (Dutch part)<\/option><option value=\"SK\">Slovakia<\/option><option value=\"SI\">Slovenia<\/option><option value=\"SB\">Solomon Islands<\/option><option value=\"SO\">Somalia<\/option><option value=\"ZA\">South Africa<\/option><option value=\"GS\">South Georgia and the South Sandwich Islands<\/option><option value=\"SS\">South Sudan<\/option><option value=\"ES\">Spain<\/option><option value=\"LK\">Sri Lanka<\/option><option value=\"SD\">Sudan<\/option><option value=\"SR\">Suriname<\/option><option value=\"SJ\">Svalbard and Jan Mayen<\/option><option value=\"SZ\">Swaziland<\/option><option value=\"CH\">Switzerland<\/option><option value=\"SE\">Sweden<\/option><option value=\"SY\">Syrian Arab Republic<\/option><option value=\"TW\">Taiwan, Province of China<\/option><option value=\"TJ\">Tajikistan<\/option><option value=\"TZ\">Tanzania, United Republic of<\/option><option value=\"TH\">Thailand<\/option><option value=\"TL\">Timor-Leste<\/option><option value=\"TG\">Togo<\/option><option value=\"TK\">Tokelau<\/option><option value=\"TO\">Tonga<\/option><option value=\"TT\">Trinidad and Tobago<\/option><option value=\"TN\">Tunisia<\/option><option value=\"TR\">Turkey<\/option><option value=\"TM\">Turkmenistan<\/option><option value=\"TC\">Turks and Caicos Islands<\/option><option value=\"TV\">Tuvalu<\/option><option value=\"UG\">Uganda<\/option><option value=\"UA\">Ukraine<\/option><option value=\"AE\">United Arab Emirates<\/option><option value=\"GB\">United Kingdom<\/option><option value=\"US\">United States<\/option><option value=\"UM\">United States Minor Outlying Islands<\/option><option value=\"UY\">Uruguay<\/option><option value=\"UZ\">Uzbekistan<\/option><option value=\"VU\">Vanuatu<\/option><option value=\"VE\">Venezuela, Bolivarian Republic of<\/option><option value=\"VN\">Viet Nam<\/option><option value=\"VG\">Virgin Islands, British<\/option><option value=\"VI\">Virgin Islands, U.S.<\/option><option value=\"WF\">Wallis and Futuna<\/option><option value=\"EH\">Western Sahara<\/option><option value=\"YE\">Yemen<\/option><option value=\"ZM\">Zambia<\/option><option value=\"ZW\">Zimbabwe<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<input class=\"wpcf7-form-control wpcf7-hidden country-code-auto\" value=\"\" type=\"hidden\" name=\"country-code\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden bpa-office-auto\" value=\"\" type=\"hidden\" name=\"bpa-sales-office\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden form-timestamp\" value=\"\" type=\"hidden\" name=\"form-timestamp\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden market-type\" value=\"\" type=\"hidden\" name=\"market-type\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden Timezone\" value=\"\" type=\"hidden\" name=\"timezone\" \/>\n\t<div class=\"company-continer phone-container\">\n\t\t<div class=\"cont\">\n\t\t\t<p><label>Direct Phone <span class=\"req\">*<\/span><\/label>\n\t\t\t<\/p>\n\t\t\t<div class=\"ph-number updated-ph-field\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"ph-number\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-phonetext wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-phonetext\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Direct Phone\" value=\"\" type=\"text\" name=\"ph-number\" \/><input type=\"hidden\" name=\"ph-number-country-code\" class=\"wpcf7-phonetext-country-code\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"submit-container\">\n\t\t\t<div class=\"checkbox-container\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"term_and_conditions\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"term_and_conditions\" value=\"1\" class=\"required\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I have read and consent to the BPA Solutions<a href=\"https:\/\/www.bpa-solutions.net\/privacy-policy\/\" target=\"_blank\"> Privacy Policy<\/a>.*<\/span><\/label><\/span><\/span><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div style=\"display:none;\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"page-url\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"https:\/\/www.bpa-solutions.net\/fr\/fr\/wp-json\/wp\/v2\/pages\/30149\" type=\"text\" name=\"page-url\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div style=\"display:none;\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"bpa-software\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"BPA Quality 365\" type=\"text\" name=\"bpa-software\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"btn-container\" >\n\t\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" id=\"get-brochure-cta\" type=\"submit\" value=\"Get the brochure now\" \/>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; module_id=&#8221;#FAQ-form&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; width_tablet=&#8221;90%&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;1600px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;50px||35px||false|false&#8221; custom_margin_tablet=&#8221;25px||25px||false|false&#8221; custom_margin_phone=&#8221;||0px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,2_3&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Row&#8221; module_id=&#8221;Guidebook-form&#8221; module_class=&#8221;contact-form-section free-trial-sec &#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;50px||||false|false&#8221; custom_margin_tablet=&#8221;25px||||false|false&#8221; custom_margin_phone=&#8221;25px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;46deg&#8221; background_color_gradient_stops=&#8221;#6b8a44 1%|#bbd983 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2024\/04\/Background1.png&#8221; background_blend=&#8221;multiply&#8221; custom_padding=&#8221;35px|35px|35px|35px|false|false&#8221; sticky_position=&#8221;top&#8221; sticky_limit_bottom=&#8221;row&#8221; sticky_position_tablet=&#8221;top&#8221; sticky_position_phone=&#8221;none&#8221; sticky_position_last_edited=&#8221;on|desktop&#8221; border_radii=&#8221;off|12px|||12px&#8221; border_radii_tablet=&#8221;off|12px|||12px&#8221; border_radii_phone=&#8221;on|0px|0px|0px|0px&#8221; border_radii_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;form-text&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.3em&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_6_text_color=&#8221;#FFFFFF&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6 style=\"text-align: left;\">Download our practical guidebook to explore a detailed feature-to-standard mapping<\/h6>\n<p style=\"text-align: left;\">and discover how ISO 13485 compliance can be embedded into daily operations, supporting certification, long-term compliance, and a stronger information security posture.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;35px|35px|35px|35px|false|false&#8221; border_radii=&#8221;off||12px|12px|12px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;rgba(217,217,217,0.56)&#8221; border_radii_tablet=&#8221;off||12px|12px|12px&#8221; border_radii_phone=&#8221;on|0px|0px|0px|0px&#8221; border_radii_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Get in touch!&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h6&#8243; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_code module_class=&#8221;free-trial-form&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f30155-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"30155\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/30149#wpcf7-f30155-o2\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"30155\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f30155-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"free-trial-form\">\n\t<div class=\"company-continer\">\n\t\t<div class=\"cont\">\n\t\t\t<p><label> Business Email<span class=\"req\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Work Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"company-continer\">\n\t\t<div class=\"cont\">\n\t\t\t<p><label> First Name<span class=\"req\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"First Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"cont\">\n\t\t\t<p><label> Last Name<span class=\"req\">*<\/span> <\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"lastname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Last Name\" value=\"\" type=\"text\" name=\"lastname\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"company-continer phone-container\">\n\t\t<div class=\"cont\">\n\t\t\t<p><label>Direct Phone <span class=\"req\">*<\/span><\/label>\n\t\t\t<\/p>\n\t\t\t<div class=\"ph-number updated-ph-field\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"ph-number\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-phonetext wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-phonetext\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Direct Phone\" value=\"\" type=\"text\" name=\"ph-number\" \/><input type=\"hidden\" name=\"ph-number-country-code\" class=\"wpcf7-phonetext-country-code\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"company-continer\">\n\t\t<div class=\"cont\">\n\t\t\t<p><label>Company<span class=\"req\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company Name\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"cont company-select search-drop-cont\">\n\t\t\t<p><label>Country <span class=\"req\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"select-country\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required country-dropdown\" id=\"search-dropdown\" aria-required=\"true\" aria-invalid=\"false\" name=\"select-country\"><option value=\"\">Country<\/option><option value=\"US\">United States<\/option><option value=\"AF\">Afghanistan<\/option><option value=\"AX\">\u00c5land Islands<\/option><option value=\"AL\">Albania<\/option><option value=\"DZ\">Algeria<\/option><option value=\"AS\">American Samoa<\/option><option value=\"AD\">Andorra<\/option><option value=\"AO\">Angola<\/option><option value=\"AI\">Anguilla<\/option><option value=\"AG\">Antigua and Barbuda<\/option><option value=\"AR\">Argentina<\/option><option value=\"AM\">Armenia<\/option><option value=\"AW\">Aruba<\/option><option value=\"AC\">Ascension<\/option><option value=\"AU\">Australia<\/option><option value=\"AT\">Austria<\/option><option value=\"AZ\">Azerbaijan<\/option><option value=\"BS\">Bahamas<\/option><option value=\"BH\">Bahrain<\/option><option value=\"BB\">Barbados<\/option><option value=\"BY\">Belarus<\/option><option value=\"BE\">Belgium<\/option><option value=\"BZ\">Belize<\/option><option value=\"BJ\">Benin<\/option><option value=\"BM\">Bermuda<\/option><option value=\"BT\">Bhutan<\/option><option value=\"BO\">Bolivia, Plurinational State of<\/option><option value=\"BQ\">Bonaire, Sint Eustatius and Saba<\/option><option value=\"BA\">Bosnia and Herzegovina<\/option><option value=\"BW\">Botswana<\/option><option value=\"BR\">Brazil<\/option><option value=\"IO\">British Indian Ocean Territory<\/option><option value=\"BN\">Brunei Darussalam<\/option><option value=\"BG\">Bulgaria<\/option><option value=\"BF\">Burkina Faso<\/option><option value=\"BI\">Burundi<\/option><option value=\"KH\">Cambodia<\/option><option value=\"CM\">Cameroon<\/option><option value=\"CA\">Canada<\/option><option value=\"IC\">Canary Islands<\/option><option value=\"CV\">Cape Verde<\/option><option value=\"KY\">Cayman Islands<\/option><option value=\"CF\">Central African Republic<\/option><option value=\"TD\">Chad<\/option><option value=\"CL\">Chile<\/option><option value=\"CN\">China<\/option><option value=\"CX\">Christmas Island<\/option><option value=\"CC\">Cocos (Keeling) Islands<\/option><option value=\"CO\">Colombia<\/option><option value=\"KM\">Comoros<\/option><option value=\"CG\">Congo<\/option><option value=\"CD\">Congo, the Democratic Republic of the<\/option><option value=\"CK\">Cook Islands<\/option><option value=\"CR\">Costa Rica<\/option><option value=\"CI\">C\u00f4te d&#039;Ivoire<\/option><option value=\"HR\">Croatia<\/option><option value=\"CU\">Cuba<\/option><option value=\"CW\">Cura\u00e7ao<\/option><option value=\"CY\">Cyprus<\/option><option value=\"CZ\">Czech Republic<\/option><option value=\"DK\">Denmark<\/option><option value=\"DG\">Diego Garcia<\/option><option value=\"DJ\">Djibouti<\/option><option value=\"DM\">Dominica<\/option><option value=\"DO\">Dominican Republic<\/option><option value=\"EC\">Ecuador<\/option><option value=\"EG\">Egypt<\/option><option value=\"SV\">El Salvador<\/option><option value=\"GQ\">Equatorial Guinea<\/option><option value=\"ER\">Eritrea<\/option><option value=\"EE\">Estonia<\/option><option value=\"ET\">Ethiopia<\/option><option value=\"FK\">Falkland Islands (Malvinas)<\/option><option value=\"FO\">Faroe Islands<\/option><option value=\"FJ\">Fiji<\/option><option value=\"FI\">Finland<\/option><option value=\"FR\">France<\/option><option value=\"GF\">French Guiana<\/option><option value=\"PF\">French Polynesia<\/option><option value=\"GA\">Gabon<\/option><option value=\"GM\">Gambia<\/option><option value=\"GE\">Georgia<\/option><option value=\"DE\">Germany<\/option><option value=\"GH\">Ghana<\/option><option value=\"GI\">Gibraltar<\/option><option value=\"GR\">Greece<\/option><option value=\"GL\">Greenland<\/option><option value=\"GD\">Grenada<\/option><option value=\"GP\">Guadeloupe<\/option><option value=\"GU\">Guam<\/option><option value=\"GT\">Guatemala<\/option><option value=\"GG\">Guernsey<\/option><option value=\"GN\">Guinea<\/option><option value=\"GW\">Guinea-Bissau<\/option><option value=\"GY\">Guyana<\/option><option value=\"HT\">Haiti<\/option><option value=\"HM\">Heard Island and McDonald Islands<\/option><option value=\"VA\">Holy See (Vatican City State)<\/option><option value=\"HN\">Honduras<\/option><option value=\"HK\">Hong Kong<\/option><option value=\"HU\">Hungary<\/option><option value=\"IS\">Iceland<\/option><option value=\"ID\">Indonesia<\/option><option value=\"IR\">Iran, Islamic Republic of<\/option><option value=\"IQ\">Iraq<\/option><option value=\"IE\">Ireland<\/option><option value=\"IM\">Isle of Man<\/option><option value=\"IL\">Israel<\/option><option value=\"IT\">Italy<\/option><option value=\"JM\">Jamaica<\/option><option value=\"JP\">Japan<\/option><option value=\"JE\">Jersey<\/option><option value=\"JO\">Jordan<\/option><option value=\"KZ\">Kazakhstan<\/option><option value=\"KE\">Kenya<\/option><option value=\"KI\">Kiribati<\/option><option value=\"KP\">Korea, Democratic People&#039;s Republic of<\/option><option value=\"KR\">Korea, Republic of<\/option><option value=\"KW\">Kuwait<\/option><option value=\"KG\">Kyrgyzstan<\/option><option value=\"LA\">Lao People&#039;s Democratic Republic<\/option><option value=\"LV\">Latvia<\/option><option value=\"LB\">Lebanon<\/option><option value=\"LS\">Lesotho<\/option><option value=\"LR\">Liberia<\/option><option value=\"LY\">Libya<\/option><option value=\"LI\">Liechtenstein<\/option><option value=\"LT\">Lithuania<\/option><option value=\"LU\">Luxembourg<\/option><option value=\"MO\">Macao<\/option><option value=\"MK\">Macedonia, the former Yugoslav Republic of<\/option><option value=\"MG\">Madagascar<\/option><option value=\"MW\">Malawi<\/option><option value=\"MY\">Malaysia<\/option><option value=\"MV\">Maldives<\/option><option value=\"ML\">Mali<\/option><option value=\"MT\">Malta<\/option><option value=\"MH\">Marshall Islands<\/option><option value=\"MQ\">Martinique<\/option><option value=\"MR\">Mauritania<\/option><option value=\"MU\">Mauritius<\/option><option value=\"YT\">Mayotte<\/option><option value=\"MX\">Mexico<\/option><option value=\"FM\">Micronesia, Federated States of<\/option><option value=\"MD\">Moldova, Republic of<\/option><option value=\"MC\">Monaco<\/option><option value=\"MN\">Mongolia<\/option><option value=\"ME\">Montenegro<\/option><option value=\"MS\">Montserrat<\/option><option value=\"MA\">Morocco<\/option><option value=\"MZ\">Mozambique<\/option><option value=\"MM\">Myanmar<\/option><option value=\"NA\">Namibia<\/option><option value=\"NR\">Nauru<\/option><option value=\"NP\">Nepal<\/option><option value=\"NL\">Netherlands<\/option><option value=\"AN\">Netherlands Antilles<\/option><option value=\"NC\">New Caledonia<\/option><option value=\"NZ\">New Zealand<\/option><option value=\"NI\">Nicaragua<\/option><option value=\"NE\">Niger<\/option><option value=\"NG\">Nigeria<\/option><option value=\"NU\">Niue<\/option><option value=\"NF\">Norfolk Island<\/option><option value=\"MP\">Northern Mariana Islands<\/option><option value=\"NO\">Norway<\/option><option value=\"OM\">Oman<\/option><option value=\"PW\">Palau<\/option><option value=\"PS\">Palestinian Territory, Occupied<\/option><option value=\"PA\">Panama<\/option><option value=\"PG\">Papua New Guinea<\/option><option value=\"PY\">Paraguay<\/option><option value=\"PE\">Peru<\/option><option value=\"PH\">Philippines<\/option><option value=\"PN\">Pitcairn<\/option><option value=\"PL\">Poland<\/option><option value=\"PT\">Portugal<\/option><option value=\"PR\">Puerto Rico<\/option><option value=\"QA\">Qatar<\/option><option value=\"RE\">R\u00e9union<\/option><option value=\"RO\">Romania<\/option><option value=\"RU\">Russian Federation<\/option><option value=\"RW\">Rwanda<\/option><option value=\"BL\">Saint Barth\u00e9lemy<\/option><option value=\"SH\">Saint Helena, Ascension and Tristan da Cunha<\/option><option value=\"KN\">Saint Kitts and Nevis<\/option><option value=\"LC\">Saint Lucia<\/option><option value=\"MF\">Saint Martin (French part)<\/option><option value=\"PM\">Saint Pierre and Miquelon<\/option><option value=\"VC\">Saint Vincent and the Grenadines<\/option><option value=\"WS\">Samoa<\/option><option value=\"SM\">San Marino<\/option><option value=\"ST\">Sao Tome and Principe<\/option><option value=\"SA\">Saudi Arabia<\/option><option value=\"NT\">Saudi\u2013Iraqi neutral zone<\/option><option value=\"SN\">Senegal<\/option><option value=\"RS\">Serbia<\/option><option value=\"SC\">Seychelles<\/option><option value=\"SL\">Sierra Leone<\/option><option value=\"SG\">Singapore<\/option><option value=\"SX\">Sint Maarten (Dutch part)<\/option><option value=\"SK\">Slovakia<\/option><option value=\"SI\">Slovenia<\/option><option value=\"SB\">Solomon Islands<\/option><option value=\"SO\">Somalia<\/option><option value=\"ZA\">South Africa<\/option><option value=\"GS\">South Georgia and the South Sandwich Islands<\/option><option value=\"SS\">South Sudan<\/option><option value=\"ES\">Spain<\/option><option value=\"LK\">Sri Lanka<\/option><option value=\"SD\">Sudan<\/option><option value=\"SR\">Suriname<\/option><option value=\"SJ\">Svalbard and Jan Mayen<\/option><option value=\"SZ\">Swaziland<\/option><option value=\"CH\">Switzerland<\/option><option value=\"SE\">Sweden<\/option><option value=\"SY\">Syrian Arab Republic<\/option><option value=\"TW\">Taiwan, Province of China<\/option><option value=\"TJ\">Tajikistan<\/option><option value=\"TZ\">Tanzania, United Republic of<\/option><option value=\"TH\">Thailand<\/option><option value=\"TL\">Timor-Leste<\/option><option value=\"TG\">Togo<\/option><option value=\"TK\">Tokelau<\/option><option value=\"TO\">Tonga<\/option><option value=\"TT\">Trinidad and Tobago<\/option><option value=\"TN\">Tunisia<\/option><option value=\"TR\">Turkey<\/option><option value=\"TM\">Turkmenistan<\/option><option value=\"TC\">Turks and Caicos Islands<\/option><option value=\"TV\">Tuvalu<\/option><option value=\"UG\">Uganda<\/option><option value=\"UA\">Ukraine<\/option><option value=\"AE\">United Arab Emirates<\/option><option value=\"GB\">United Kingdom<\/option><option value=\"US\">United States<\/option><option value=\"UM\">United States Minor Outlying Islands<\/option><option value=\"UY\">Uruguay<\/option><option value=\"UZ\">Uzbekistan<\/option><option value=\"VU\">Vanuatu<\/option><option value=\"VE\">Venezuela, Bolivarian Republic of<\/option><option value=\"VN\">Viet Nam<\/option><option value=\"VG\">Virgin Islands, British<\/option><option value=\"VI\">Virgin Islands, U.S.<\/option><option value=\"WF\">Wallis and Futuna<\/option><option value=\"EH\">Western Sahara<\/option><option value=\"YE\">Yemen<\/option><option value=\"ZM\">Zambia<\/option><option value=\"ZW\">Zimbabwe<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<input class=\"wpcf7-form-control wpcf7-hidden country-code-auto\" value=\"\" type=\"hidden\" name=\"country-code\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden bpa-office-auto\" value=\"\" type=\"hidden\" name=\"bpa-sales-office\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden form-timestamp\" value=\"\" type=\"hidden\" name=\"form-timestamp\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden market-type\" value=\"\" type=\"hidden\" name=\"market-type\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden Timezone\" value=\"\" type=\"hidden\" name=\"timezone\" \/>\n\t<div class=\"company-continer\">\n\t\t<div class=\"product-container cont company-select select-prod-arrow\">\n\t\t\t<p><label>Which solution are you interested in? <span class=\"req\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"product\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"product\"><option value=\"\">Which solution are you interested in?<\/option><option value=\"BPA Quality 365\">BPA Quality 365<\/option><option value=\"BPA Medical 365\">BPA Medical 365<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"comment-container\">\n\t\t<div class=\"cont\">\n\t\t\t<p><label>Comments <span class=\"req\">*<\/span><\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Comments\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"submit-container\">\n\t\t<div class=\"checkbox-container\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"term_and_conditions\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"term_and_conditions\" value=\"1\" class=\"required\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I have read and consent to the BPA Solutions<a href=\"https:\/\/www.bpa-solutions.net\/privacy-policy\/\" target=\"_blank\"> Privacy Policy<\/a>.*<\/span><\/label><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div style=\"display:none;\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"page-url\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"https:\/\/www.bpa-solutions.net\/fr\/fr\/wp-json\/wp\/v2\/pages\/30149\" type=\"text\" name=\"page-url\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"btn-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Download guidebook\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<p><span id=\"wpcf7-6a579c111f498-wrapper\" class=\"wpcf7-form-control-wrap email-wrap\" data-cf7apps-honeypot=\"email\" style=\"display: block;\n\t\t    width: 0px;\n\t\t    height: 0px;\n\t\t    padding: 0px;\n\t\t    border: 1px solid transparent;\n\t\t    display: block;\n\t\t    overflow: hidden;\n\t\t    \"><input type=\"hidden\" name=\"email-random-hash\" value=\"49439510\"><label\n\t\t    for=\"wpcf7-6a579c111f498-field\"\n\t\t    class=\"hp-message\"\n        >Please leave this field empty.<\/label><input\n\t    id=\"wpcf7-6a579c111f498-field\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"qs9crdqtq7ip\"\n\t    value=\"\"\n\t    size=\"40\"\n\t    autocomplete=\"new-password\"\n\t    tabindex=\"1000\"\n    \/><\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span><span><a href=\"https:\/\/www.bpa-solutions.net\/\">Home<\/a><\/span><\/span>ISO 13485:2016 is the international benchmark for quality management systems in the medical device industry, defining strict requirements to ensure product safety, regulatory compliance, and full traceability across the product life cycle. As global regulations increasingly align with ISO 13485, organizations must implement structured, risk based, and audit ready processes that go beyond documentation and [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":30052,"parent":30164,"menu_order":122,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"<p>[av_three_fourth first]<\/p><p>[av_textblock size='' font_color='' color='']<\/p><h1>For Us, Good Enough is not Good Enough !<\/h1><p>As a previous service company, it\u2019s in our culture to serve customers with excellence. Good enough is not good enough for us!<\/p><p>BPA and BPA certified Partners will help you implement our solutions worldwide to work the way you work. We can do it all or provide world class customized training to fit your needs.<\/p><p>We offer a full range of professional services, including:<\/p><ul><li>Training<\/li><li>Configuration<\/li><li>Installation<\/li><li>Data migration<\/li><li>Coaching & consulting<\/li><li>Project management<\/li><\/ul><p>Please<a href=\"https:\/\/www.bpa-solutions.net\/contact-us\/\"> contact <\/a> us to learn more about BPA Professional Services.<br \/>[\/av_textblock]<\/p><p>[\/av_three_fourth][av_one_fourth min_height='' vertical_alignment='' space='' custom_margin='' margin='0px' padding='0px' border='' border_color='' radius='0px' background_color='' src='' background_position='top left' background_repeat='no-repeat' animation='']<br \/>[av_textblock ]<\/p><div class=\"home\"><blockquote cite=\"Era Helicopters \u2013 United States\"><p>It only took 4 weeks to customize the system, after a couple of hours of training our sales team was good to go and started using the system immediately..<\/p><\/blockquote><\/div><p>[\/av_textblock]<br \/>[\/av_one_fourth]<\/p>","_et_gb_content_width":"","content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-30149","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BPA for ISO 13485 compliance | #1 eQMS on SharePoint<\/title>\n<meta name=\"description\" content=\"Discover how ISO 13485 compliance can be embedded into daily operations, supporting certification and long-term compliance with BPA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bpa-solutions.net\/fr\/compliance-with-bpa\/compliance-with-iso13485\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BPA for ISO 13485 compliance | #1 eQMS on SharePoint\" \/>\n<meta property=\"og:description\" content=\"Discover how ISO 13485 compliance can be embedded into daily operations, supporting certification and long-term compliance with BPA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bpa-solutions.net\/fr\/compliance-with-bpa\/compliance-with-iso13485\/\" \/>\n<meta property=\"og:site_name\" content=\"BPA Solutions\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BPASolutions?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-17T13:44:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-19-093025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1308\" \/>\n\t<meta property=\"og:image:height\" content=\"849\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BPA_SOLUTIONS\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/compliance-with-bpa\\\/compliance-with-iso13485\\\/\",\"url\":\"https:\\\/\\\/www.bpa-solutions.net\\\/compliance-with-bpa\\\/compliance-with-iso13485\\\/\",\"name\":\"BPA for ISO 13485 compliance | #1 eQMS on SharePoint\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/compliance-with-bpa\\\/compliance-with-iso13485\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/compliance-with-bpa\\\/compliance-with-iso13485\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bpa-solutions.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Screenshot-2026-01-19-093025.png\",\"datePublished\":\"2026-02-13T15:40:38+00:00\",\"dateModified\":\"2026-02-17T13:44:37+00:00\",\"description\":\"Discover how ISO 13485 compliance can be embedded into daily operations, supporting certification and long-term compliance with BPA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/compliance-with-bpa\\\/compliance-with-iso13485\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bpa-solutions.net\\\/compliance-with-bpa\\\/compliance-with-iso13485\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/compliance-with-bpa\\\/compliance-with-iso13485\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bpa-solutions.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Screenshot-2026-01-19-093025.png\",\"contentUrl\":\"https:\\\/\\\/www.bpa-solutions.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Screenshot-2026-01-19-093025.png\",\"width\":1308,\"height\":849,\"caption\":\"How BPA streamlines compliance efficiently\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/compliance-with-bpa\\\/compliance-with-iso13485\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bpa-solutions.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compliance with BPA\",\"item\":\"https:\\\/\\\/www.bpa-solutions.net\\\/compliance-with-bpa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Compliance with ISO13485\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/#website\",\"url\":\"https:\\\/\\\/www.bpa-solutions.net\\\/\",\"name\":\"BPA Solutions\",\"description\":\"Intuitive, secure, intelligent eQMS on SharePoint Microsoft 365 AI\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bpa-solutions.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/#organization\",\"name\":\"BPA Solutions\",\"url\":\"https:\\\/\\\/www.bpa-solutions.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bpa-solutions.net\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/BPA-Solutions.svg\",\"contentUrl\":\"https:\\\/\\\/www.bpa-solutions.net\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/BPA-Solutions.svg\",\"width\":301,\"height\":68,\"caption\":\"BPA Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bpa-solutions.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BPASolutions?fref=ts\",\"https:\\\/\\\/x.com\\\/BPA_SOLUTIONS\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BPA for ISO 13485 compliance | #1 eQMS on SharePoint","description":"Discover how ISO 13485 compliance can be embedded into daily operations, supporting certification and long-term compliance with BPA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bpa-solutions.net\/fr\/compliance-with-bpa\/compliance-with-iso13485\/","og_locale":"fr_FR","og_type":"article","og_title":"BPA for ISO 13485 compliance | #1 eQMS on SharePoint","og_description":"Discover how ISO 13485 compliance can be embedded into daily operations, supporting certification and long-term compliance with BPA.","og_url":"https:\/\/www.bpa-solutions.net\/fr\/compliance-with-bpa\/compliance-with-iso13485\/","og_site_name":"BPA Solutions","article_publisher":"https:\/\/www.facebook.com\/BPASolutions?fref=ts","article_modified_time":"2026-02-17T13:44:37+00:00","og_image":[{"width":1308,"height":849,"url":"https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-19-093025.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@BPA_SOLUTIONS","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bpa-solutions.net\/compliance-with-bpa\/compliance-with-iso13485\/","url":"https:\/\/www.bpa-solutions.net\/compliance-with-bpa\/compliance-with-iso13485\/","name":"BPA for ISO 13485 compliance | #1 eQMS on SharePoint","isPartOf":{"@id":"https:\/\/www.bpa-solutions.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bpa-solutions.net\/compliance-with-bpa\/compliance-with-iso13485\/#primaryimage"},"image":{"@id":"https:\/\/www.bpa-solutions.net\/compliance-with-bpa\/compliance-with-iso13485\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-19-093025.png","datePublished":"2026-02-13T15:40:38+00:00","dateModified":"2026-02-17T13:44:37+00:00","description":"Discover how ISO 13485 compliance can be embedded into daily operations, supporting certification and long-term compliance with BPA.","breadcrumb":{"@id":"https:\/\/www.bpa-solutions.net\/compliance-with-bpa\/compliance-with-iso13485\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bpa-solutions.net\/compliance-with-bpa\/compliance-with-iso13485\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bpa-solutions.net\/compliance-with-bpa\/compliance-with-iso13485\/#primaryimage","url":"https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-19-093025.png","contentUrl":"https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-19-093025.png","width":1308,"height":849,"caption":"How BPA streamlines compliance efficiently"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bpa-solutions.net\/compliance-with-bpa\/compliance-with-iso13485\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bpa-solutions.net\/"},{"@type":"ListItem","position":2,"name":"Compliance with BPA","item":"https:\/\/www.bpa-solutions.net\/compliance-with-bpa\/"},{"@type":"ListItem","position":3,"name":"Compliance with ISO13485"}]},{"@type":"WebSite","@id":"https:\/\/www.bpa-solutions.net\/#website","url":"https:\/\/www.bpa-solutions.net\/","name":"Solutions BPA","description":"Intuitive, secure, intelligent eQMS on SharePoint Microsoft 365 AI","publisher":{"@id":"https:\/\/www.bpa-solutions.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bpa-solutions.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bpa-solutions.net\/#organization","name":"Solutions BPA","url":"https:\/\/www.bpa-solutions.net\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bpa-solutions.net\/#\/schema\/logo\/image\/","url":"https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2023\/05\/BPA-Solutions.svg","contentUrl":"https:\/\/www.bpa-solutions.net\/wp-content\/uploads\/2023\/05\/BPA-Solutions.svg","width":301,"height":68,"caption":"BPA Solutions"},"image":{"@id":"https:\/\/www.bpa-solutions.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BPASolutions?fref=ts","https:\/\/x.com\/BPA_SOLUTIONS"]}]}},"_links":{"self":[{"href":"https:\/\/www.bpa-solutions.net\/fr\/wp-json\/wp\/v2\/pages\/30149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bpa-solutions.net\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bpa-solutions.net\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bpa-solutions.net\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bpa-solutions.net\/fr\/wp-json\/wp\/v2\/comments?post=30149"}],"version-history":[{"count":0,"href":"https:\/\/www.bpa-solutions.net\/fr\/wp-json\/wp\/v2\/pages\/30149\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.bpa-solutions.net\/fr\/wp-json\/wp\/v2\/pages\/30164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bpa-solutions.net\/fr\/wp-json\/wp\/v2\/media\/30052"}],"wp:attachment":[{"href":"https:\/\/www.bpa-solutions.net\/fr\/wp-json\/wp\/v2\/media?parent=30149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}